{"id":6645,"date":"2021-01-26T17:01:37","date_gmt":"2021-01-26T16:01:37","guid":{"rendered":"https:\/\/lindemannlaw.ch\/swiss-fund-tax-reporting-for-foreign-investment-funds-no-longer-a-walk-in-the-park-2\/"},"modified":"2023-10-31T14:43:44","modified_gmt":"2023-10-31T13:43:44","slug":"fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante","status":"publish","type":"post","link":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/","title":{"rendered":"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9?"},"content":{"rendered":"<p><strong>R\u00e9ponses aux 5 questions les plus fr\u00e9quemment pos\u00e9es <\/strong><br \/>\nLes gestionnaire du fonds \u00e9trangers subissent actuellement de la part de l\u2019administration des contr\u00f4les plus stricts des valeurs fiscales des fonds de placement \u00e9trangers. L\u2019AFS menace parfois m\u00eame de \u201e\u00e9jecter\u201c les fonds \u00e9trangers de la cotation. Trouvez ci-apr\u00e8s les r\u00e9ponses aux 5 questions les plus fr\u00e9quemment pos\u00e9es \u00e0 propos des incidences pour les fonds de placement \u00e9trangers:<\/p>\n<p><strong>1. Que signifie le Fund Tax Reporting en Suisse ? <\/strong><br \/>\nLes investisseurs suisses sont tenus de d\u00e9poser leur d\u00e9claration fiscale jusqu\u2019en mars ou mai de l\u2019ann\u00e9e suivante avec une liste des placements de capitaux, y compris des fonds de placement. A cette fin, ils ont besoin des valeurs fiscales du fonds (selon la nouvelle terminologie : \u201eFund Tax Reporting\u201c). Lorsque la d\u00e9termination est faite en temps utile, on peut faire valoir diff\u00e9rents privil\u00e8ges fiscaux, par ex. les gains en capital peuvent \u00eatre exclus du calcul. En outre, pour les fonds distribuant des dividendes, jusqu\u2019\u00e0 30 % du produit ordinaire des int\u00e9r\u00eats et des dividendes est exon\u00e9r\u00e9 de l\u2019imp\u00f4t. L\u2019absence des valeurs fiscales du fonds g\u00e9n\u00e8re pour les investisseurs des co\u00fbts suppl\u00e9mentaires li\u00e9s \u00e0 la n\u00e9cessit\u00e9 de r\u00e9pondre \u00e0 des questions ou au m\u00e9contentement caus\u00e9 par la taxation d\u2019office par l\u2019administration fiscale. Abstraction faite des ennuis \u00e0 \u00e9viter pour les investisseurs, la publication pr\u00e9cise et dans les d\u00e9lais des Fund Tax Reportings sur le site Internet de l\u2019AFS (www.ictax.admin.ch) offre la possibilit\u00e9 d\u2019une commercialisation gratuite avec le tampon officiel de la Direction des Finances suisse.<\/p>\n<p><strong>2. Pourquoi l\u2019administration suisse renforce-t-elle ses contr\u00f4les ?<\/strong><br \/>\nD\u2019une part, le nombre des fonds de placement \u00e9trangers en Suisse est en hausse. D\u2019autre part, la Suisse am\u00e9liore la protection des investisseurs en renfor\u00e7ant \u00e0 la fois les obligations des repr\u00e9sentants des fonds dans la commercialisation aupr\u00e8s d\u2019investisseurs qualifi\u00e9s et dans leur contr\u00f4le par la FINMA. La p\u00e9riode de transition court jusqu\u2019\u00e0 la fin f\u00e9vrier 2015. Suite \u00e0 la r\u00e9vision du droit p\u00e9nal fiscal, la tendance aux contr\u00f4les fiscaux s\u2019accro\u00eet avec l\u2019acc\u00e8s aux informations bancaires de l\u2019administration fiscale cantonale, avec des sanctions aggrav\u00e9es (y compris le d\u00e9tention contre l&rsquo;\u00e9vasion fiscale. L\u2019administration fiscale cantonale traite chaque ann\u00e9e entre 4 000 \u00e0 6 000 proc\u00e9dures de fraude fiscale, ainsi que des milliers de cas suppl\u00e9mentaires de d\u00e9nonciation spontan\u00e9e (rien qu\u2019en 2013, plus de 5300 personnes), avec une tendance \u00e0 la hausse ! Le simple volume de fonds de plusieurs centaines de milliards de CHF exerce ainsi des cons\u00e9quences fiscales significatives.<\/p>\n<p><strong>3. Quelle est l\u2019incidence de la publication sur le site Internet de l\u2019AFS ? <\/strong><br \/>\nL\u2019administration fiscale cantonale prend en consid\u00e9ration les valeurs fiscales publi\u00e9es sur le site Internet de l\u2019AFS si elles sont fournies en temps utile. Des valeurs fiscales manquantes sur le fonds cr\u00e9ent pour les investisseurs des co\u00fbts suppl\u00e9mentaires en raison des demandes de renseignements ou du m\u00e9contentement caus\u00e9 par les estimations fiscales forfaitaires de l\u2019administration fiscale. Les valeurs publi\u00e9es par l\u2019AFS ne sont d\u00e9finitives que dans la mesure o\u00f9 elles sont correctes. Des corrections peuvent y \u00eatre apport\u00e9es \u00e0 tout moment, par ex. lorsque la valeur avait \u00e9t\u00e9 initialement fix\u00e9e forfaitairement et que les calculs ont \u00e9t\u00e9 communiqu\u00e9s plus tard, ou lorsque l\u2019administration fiscale cantonale constate des erreurs manifestes. Les valeurs initiales et leurs corrections avec une date restent d\u00e9finitivement visibles sur le site Internet de l\u2019AFS.<\/p>\n<p><strong>4. Que se passe-t-il en cas de non-respect des obligations de reporting ? <\/strong><br \/>\nL\u2019AFS dispose d\u2019une \u00e9quipe dont les effectifs sont tr\u00e8s limit\u00e9s et qui doit veiller sur la publication des donn\u00e9es fiscales de quelque 25 000 classes d\u2019action de fonds. Autrement dit, la d\u00e9termination forfaitaire ou l\u2019\u00e9valuation des fonds \u00e9trangers qui n\u2019ont pas d\u00e9pos\u00e9 de d\u00e9claration constitue une t\u00e2che dont elle a beaucoup de mal \u00e0 s\u2019acquitter. Conform\u00e9ment aux circulaires 24 et 25 de l\u2019AFS, les fonds de placement \u00e9trangers doivent mettre le reporting, en particulier les valeurs fiscales pour l\u2019imp\u00f4t sur le revenu et l\u2019imp\u00f4t sur la fortune, ainsi que les rapports annuels servant de base, \u00e0 la disposition aussi bien de l\u2019AFS que des investisseurs. En raison de l\u2019art. 79 alin\u00e9a 4 de l\u2019OPCC FINMA (nouvelle), selon le mode de lecture de l\u2019administration, cette obligation est \u00e9galement \u00e9largie aux repr\u00e9sentants des placements collectifs \u00e9trangers.<\/p>\n<p><strong>5. Quels sont les risques encourus par les gestionnaire du fonds ou les repr\u00e9sentants de fonds ?<\/strong><br \/>\nDepuis r\u00e9cemment, l\u2019AFS menace aussi bien les gestionnaire du fonds \u00e9trangers qui ne s\u2019acquittent pas de leurs obligations que les repr\u00e9sentants suisses du fonds de les \u201eexpulser\u201c de la cotation ou de leur retirer l\u2019homologation de la FINMA. Les repr\u00e9sentants du fonds ou les investisseurs peuvent tenus de justifier que les valeurs fiscales sont correctes, ou de calculer les valeurs fiscales manquantes \u00e0 leurs propres frais. En cas de Fund Tax Reporting manquant ou fix\u00e9 forfaitairement par l\u2019AFS, l\u2019investisseur peut s\u2019exposer \u00e0 des ennuis ou \u00e0 une dommage que peut \u00e9voquer pour les distributeurs ou des repr\u00e9sentants du fonds la responsabilit\u00e9 d\u00b4indemniser. Le Fund Tax Reporting suisse pour les fonds de placement \u00e9trangers devient ainsi un crit\u00e8re de qualit\u00e9. Les repr\u00e9sentants de placements collectifs de capitaux et leurs distributeurs devraient par cons\u00e9quent renforcer leur diligence raisonnable. Pour \u00e9viter que leur responsabilit\u00e9 ne soit engag\u00e9e s\u2019ils s\u2019abstiennent de faire leur propre Fund Tax Reporting suisse il saurait recommandable \u00e0 inclure des indications correspondantes dans les documents que le fonds adresse aux investisseurs.<\/p>\n<p><strong>Avez-vous des questions ? \u2013 Nous serions ravis si vous preniez contact avec nous !<\/strong><\/p>\n<p>Please download PDF here:<\/p>\n<p><a href=\"https:\/\/lindemannlaw.ch\/wp-content\/uploads\/2021\/01\/Fund-Tax-Reporting-suisse-pour-les-fonds-etrangers-\u2013-ce-nest-plus-une-simple-promenade-de-sante-LINDEMANNLAW.pdf\">Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9 &#8211; LINDEMANNLAW<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9ponses aux 5 questions les plus fr\u00e9quemment pos\u00e9es Les gestionnaire du fonds \u00e9trangers subissent actuellement de la part de l\u2019administration des contr\u00f4les plus stricts des valeurs fiscales des fonds de placement \u00e9trangers. L\u2019AFS menace parfois m\u00eame de \u201e\u00e9jecter\u201c les fonds \u00e9trangers de la cotation. Trouvez ci-apr\u00e8s les r\u00e9ponses aux 5 questions les plus fr\u00e9quemment pos\u00e9es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"","_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[60],"tags":[],"related_contact":[201,213],"expertise":[271,149,285,288],"class_list":["post-6645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insights"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9? | Lindemann Law<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9?\" \/>\n<meta property=\"og:description\" content=\"R\u00e9ponses aux 5 questions les plus fr\u00e9quemment pos\u00e9es Les gestionnaire du fonds \u00e9trangers subissent actuellement de la part de l\u2019administration des contr\u00f4les plus stricts des valeurs fiscales des fonds de placement \u00e9trangers. L\u2019AFS menace parfois m\u00eame de \u201e\u00e9jecter\u201c les fonds \u00e9trangers de la cotation. Trouvez ci-apr\u00e8s les r\u00e9ponses aux 5 questions les plus fr\u00e9quemment pos\u00e9es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"Lindemann Law\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-26T16:01:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-31T13:43:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lindemannlaw.ch\/wp-content\/uploads\/2020\/12\/Tax-Adler-Verlauf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"2500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"natalia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Lindemann_law\" \/>\n<meta name=\"twitter:site\" content=\"@Lindemann_law\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"natalia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/\"},\"author\":{\"name\":\"natalia\",\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/#\\\/schema\\\/person\\\/c708dfabaeb47dd1697ff9fe8461fde7\"},\"headline\":\"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9?\",\"datePublished\":\"2021-01-26T16:01:37+00:00\",\"dateModified\":\"2023-10-31T13:43:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/\"},\"wordCount\":1026,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lindemannlaw.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tax-Adler-Verlauf.jpg\",\"articleSection\":[\"Informations\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/\",\"url\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/\",\"name\":\"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9? | Lindemann Law\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lindemannlaw.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tax-Adler-Verlauf.jpg\",\"datePublished\":\"2021-01-26T16:01:37+00:00\",\"dateModified\":\"2023-10-31T13:43:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lindemannlaw.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tax-Adler-Verlauf.jpg\",\"contentUrl\":\"https:\\\/\\\/lindemannlaw.ch\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Tax-Adler-Verlauf.jpg\",\"width\":1800,\"height\":2500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/insights\\\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informations\",\"item\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/category\\\/insights\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/\",\"name\":\"Lindemann Law\",\"description\":\"Asset Management legal services\",\"publisher\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/#organization\",\"name\":\"Lindemann Law\",\"url\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lindemannlaw.ch\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-lindemannlaw_cropped.png\",\"contentUrl\":\"https:\\\/\\\/lindemannlaw.ch\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-lindemannlaw_cropped.png\",\"width\":150,\"height\":73,\"caption\":\"Lindemann Law\"},\"image\":{\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Lindemann_law\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lindemannlaw\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lindemannlaw.ch\\\/fr\\\/#\\\/schema\\\/person\\\/c708dfabaeb47dd1697ff9fe8461fde7\",\"name\":\"natalia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8167c501a34858c02e9a62eec0e4a036b451edfd3b21fec38ef9cf1b87f04af0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8167c501a34858c02e9a62eec0e4a036b451edfd3b21fec38ef9cf1b87f04af0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8167c501a34858c02e9a62eec0e4a036b451edfd3b21fec38ef9cf1b87f04af0?s=96&d=mm&r=g\",\"caption\":\"natalia\"},\"sameAs\":[\"https:\\\/\\\/lindemannlaw.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9? | Lindemann Law","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/","og_locale":"fr_FR","og_type":"article","og_title":"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9?","og_description":"R\u00e9ponses aux 5 questions les plus fr\u00e9quemment pos\u00e9es Les gestionnaire du fonds \u00e9trangers subissent actuellement de la part de l\u2019administration des contr\u00f4les plus stricts des valeurs fiscales des fonds de placement \u00e9trangers. L\u2019AFS menace parfois m\u00eame de \u201e\u00e9jecter\u201c les fonds \u00e9trangers de la cotation. Trouvez ci-apr\u00e8s les r\u00e9ponses aux 5 questions les plus fr\u00e9quemment pos\u00e9es [&hellip;]","og_url":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/","og_site_name":"Lindemann Law","article_published_time":"2021-01-26T16:01:37+00:00","article_modified_time":"2023-10-31T13:43:44+00:00","og_image":[{"width":1800,"height":2500,"url":"https:\/\/lindemannlaw.ch\/wp-content\/uploads\/2020\/12\/Tax-Adler-Verlauf.jpg","type":"image\/jpeg"}],"author":"natalia","twitter_card":"summary_large_image","twitter_creator":"@Lindemann_law","twitter_site":"@Lindemann_law","twitter_misc":{"\u00c9crit par":"natalia","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/#article","isPartOf":{"@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/"},"author":{"name":"natalia","@id":"https:\/\/lindemannlaw.ch\/fr\/#\/schema\/person\/c708dfabaeb47dd1697ff9fe8461fde7"},"headline":"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9?","datePublished":"2021-01-26T16:01:37+00:00","dateModified":"2023-10-31T13:43:44+00:00","mainEntityOfPage":{"@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/"},"wordCount":1026,"commentCount":0,"publisher":{"@id":"https:\/\/lindemannlaw.ch\/fr\/#organization"},"image":{"@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/lindemannlaw.ch\/wp-content\/uploads\/2020\/12\/Tax-Adler-Verlauf.jpg","articleSection":["Informations"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/","url":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/","name":"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9? | Lindemann Law","isPartOf":{"@id":"https:\/\/lindemannlaw.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/#primaryimage"},"image":{"@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/lindemannlaw.ch\/wp-content\/uploads\/2020\/12\/Tax-Adler-Verlauf.jpg","datePublished":"2021-01-26T16:01:37+00:00","dateModified":"2023-10-31T13:43:44+00:00","breadcrumb":{"@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/#primaryimage","url":"https:\/\/lindemannlaw.ch\/wp-content\/uploads\/2020\/12\/Tax-Adler-Verlauf.jpg","contentUrl":"https:\/\/lindemannlaw.ch\/wp-content\/uploads\/2020\/12\/Tax-Adler-Verlauf.jpg","width":1800,"height":2500},{"@type":"BreadcrumbList","@id":"https:\/\/lindemannlaw.ch\/fr\/insights\/fund-tax-reporting-suisse-pour-les-fonds-etrangers-ce-nest-plus-une-simple-promenade-de-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lindemannlaw.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Informations","item":"https:\/\/lindemannlaw.ch\/fr\/category\/insights\/"},{"@type":"ListItem","position":3,"name":"Fund Tax Reporting suisse pour les fonds \u00e9trangers \u2013 ce n\u2019est plus une simple promenade de sant\u00e9?"}]},{"@type":"WebSite","@id":"https:\/\/lindemannlaw.ch\/fr\/#website","url":"https:\/\/lindemannlaw.ch\/fr\/","name":"Lindemann Law","description":"Asset Management legal services","publisher":{"@id":"https:\/\/lindemannlaw.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lindemannlaw.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lindemannlaw.ch\/fr\/#organization","name":"Lindemann Law","url":"https:\/\/lindemannlaw.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lindemannlaw.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/lindemannlaw.ch\/wp-content\/uploads\/2021\/01\/logo-lindemannlaw_cropped.png","contentUrl":"https:\/\/lindemannlaw.ch\/wp-content\/uploads\/2021\/01\/logo-lindemannlaw_cropped.png","width":150,"height":73,"caption":"Lindemann Law"},"image":{"@id":"https:\/\/lindemannlaw.ch\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Lindemann_law","https:\/\/www.linkedin.com\/company\/lindemannlaw\/"]},{"@type":"Person","@id":"https:\/\/lindemannlaw.ch\/fr\/#\/schema\/person\/c708dfabaeb47dd1697ff9fe8461fde7","name":"natalia","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8167c501a34858c02e9a62eec0e4a036b451edfd3b21fec38ef9cf1b87f04af0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8167c501a34858c02e9a62eec0e4a036b451edfd3b21fec38ef9cf1b87f04af0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8167c501a34858c02e9a62eec0e4a036b451edfd3b21fec38ef9cf1b87f04af0?s=96&d=mm&r=g","caption":"natalia"},"sameAs":["https:\/\/lindemannlaw.ch"]}]}},"_links":{"self":[{"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/posts\/6645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/comments?post=6645"}],"version-history":[{"count":0,"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/posts\/6645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/media\/3092"}],"wp:attachment":[{"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/media?parent=6645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/categories?post=6645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/tags?post=6645"},{"taxonomy":"related_contact","embeddable":true,"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/related_contact?post=6645"},{"taxonomy":"expertise","embeddable":true,"href":"https:\/\/lindemannlaw.ch\/fr\/wp-json\/wp\/v2\/expertise?post=6645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}